{"id":3107,"count":0,"description":"","link":"http:\/\/www.heruicarbideco.com\/blog\/tag\/powder-blush-4acd-faf637\/","name":"Powder Blush","slug":"powder-blush-4acd-faf637","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/tags\/3107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/posts?tags=3107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}