{"id":3120,"count":0,"description":"","link":"http:\/\/www.heruicarbideco.com\/blog\/tag\/compact-substation-4c94-3ca1eb\/","name":"Compact Substation","slug":"compact-substation-4c94-3ca1eb","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/tags\/3120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/posts?tags=3120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}