{"id":3172,"count":0,"description":"","link":"http:\/\/www.heruicarbideco.com\/blog\/tag\/disposable-wooden-fork-4c22-ca63c9\/","name":"Disposable Wooden Fork","slug":"disposable-wooden-fork-4c22-ca63c9","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/tags\/3172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.heruicarbideco.com\/blog\/wp-json\/wp\/v2\/posts?tags=3172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}